{"id":3367121,"date":"2025-10-09T22:17:22","date_gmt":"2025-10-10T02:17:22","guid":{"rendered":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/product\/glande-electrique-chromee-de-cable-de-laiton-cable-de-8mm-diametre-de-32mm\/"},"modified":"2026-02-24T23:08:37","modified_gmt":"2026-02-24T23:08:37","slug":"glande-electrique-chromee-de-cable-de-laiton-cable-de-8mm-diametre-de-32mm","status":"publish","type":"product","link":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/product\/glande-electrique-chromee-de-cable-de-laiton-cable-de-8mm-diametre-de-32mm\/","title":{"rendered":"Glande \u00e9lectrique chrom\u00e9e de c\u00e2ble de laiton (c\u00e2ble de 8mm \/ diam\u00e8tre de 32mm)"},"content":{"rendered":"<p>Glande \u00e9lectrique chrom\u00e9e de c\u00e2ble de laiton (c\u00e2ble de 8mm \/ diam\u00e8tre de 32mm) &#8211; Gaine de c\u00e2ble \u00e9lectrique construite en laiton chrom\u00e9. Cette gaine permet aux c\u00e2bles \u00e9lectriques ainsi qu&#8217;\u00e0 d&#8217;autres types de c\u00e2bles de passer \u00e0 travers des cloisons ou sur le pont. La gaine de c\u00e2ble est dot\u00e9e d&#8217;un anneau d&#8217;\u00e9tanch\u00e9it\u00e9 qui agit comme un joint imperm\u00e9able autour du c\u00e2ble, ainsi qu&#8217;une base de fixation \u00e0 trois boulons. <\/p>\n<h3>Sp\u00e9cifications<\/h3>\n<table class=\"table\">\n<tbody>\n<tr>\n<td><strong>Marque<\/strong><\/td>\n<td>\u00c9lectrique<\/td>\n<\/tr>\n<tr>\n<td><strong>Couleur<\/strong><\/td>\n<td>Chrom\u00e9<\/td>\n<\/tr>\n<tr>\n<td><strong>Imperm\u00e9able<\/strong><\/td>\n<td>Oui<\/td>\n<\/tr>\n<tr>\n<td><strong>Construction<\/strong><\/td>\n<td>Laiton Chrom\u00e9<\/td>\n<\/tr>\n<tr>\n<td><strong>Diam\u00e8tre<\/strong><\/td>\n<td>Base de 32 mm, C\u00e2ble de 8 mm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Glande \u00e9lectrique chrom\u00e9e de c\u00e2ble de laiton (c\u00e2ble de 8mm \/ diam\u00e8tre de 32mm) &#8211; Gaine de c\u00e2ble \u00e9lectrique construite<\/p>\n","protected":false},"featured_media":5944836,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[3489],"product_cat":[1166],"product_tag":[],"class_list":{"0":"post-3367121","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-trem-fr","7":"product_cat-accessoires-electriques","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product\/3367121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/comments?post=3367121"}],"version-history":[{"count":0,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product\/3367121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/media\/5944836"}],"wp:attachment":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/media?parent=3367121"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product_brand?post=3367121"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product_cat?post=3367121"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/fr\/wp-json\/wp\/v2\/product_tag?post=3367121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}