{"id":3693998,"date":"2025-10-13T13:57:57","date_gmt":"2025-10-13T17:57:57","guid":{"rendered":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/product\/anodo-de-zinco-para-eixo-m20\/"},"modified":"2026-02-25T00:27:37","modified_gmt":"2026-02-25T00:27:37","slug":"anodo-de-zinco-para-eixo-m20","status":"publish","type":"product","link":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/product\/anodo-de-zinco-para-eixo-m20\/","title":{"rendered":"\u00c2nodo de zinco para eixo M20"},"content":{"rendered":"<p>\u00c2nodo de zinco para eixo M20 &#8211; <\/p>\n<p>Anodo ogival com rosca m\u00e9trica para eixos de h\u00e9lice.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c2nodo de zinco para eixo M20 &#8211; Anodo ogival com rosca m\u00e9trica para eixos de h\u00e9lice.<\/p>\n","protected":false},"featured_media":5936341,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[3477],"product_cat":[1926,1923],"product_tag":[],"class_list":{"0":"post-3693998","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tecnoseal-pt","7":"product_cat-anodos-de-veio","8":"product_cat-anodos-para-helice","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/3693998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/comments?post=3693998"}],"version-history":[{"count":0,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/3693998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media\/5936341"}],"wp:attachment":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media?parent=3693998"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_brand?post=3693998"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_cat?post=3693998"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_tag?post=3693998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}