{"id":3695405,"date":"2025-10-13T14:04:35","date_gmt":"2025-10-13T18:04:35","guid":{"rendered":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/product\/disjuntor-mtm-50a\/"},"modified":"2026-02-25T00:27:50","modified_gmt":"2026-02-25T00:27:50","slug":"disjuntor-mtm-50a","status":"publish","type":"product","link":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/product\/disjuntor-mtm-50a\/","title":{"rendered":"Disjuntor MTM 50A"},"content":{"rendered":"<p>Disjuntor MTM 50A &#8211; <\/p>\n<p>Disjuntor marinho Hi-Amp de montagem superficial. Combina comuta\u00e7\u00e3o e prote\u00e7\u00e3o de circuito em uma \u00fanica unidade. Classe de prote\u00e7\u00e3o IP67, \u00e0 prova d&#8217;\u00e1gua, n\u00e3o produz fa\u00edscas e pode ser usado em barcos com combust\u00edvel a gasolina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Disjuntor MTM 50A &#8211; Disjuntor marinho Hi-Amp de montagem superficial. Combina comuta\u00e7\u00e3o e prote\u00e7\u00e3o de circuito em uma \u00fanica unidade.<\/p>\n","protected":false},"featured_media":5939243,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[2832],"product_cat":[2035],"product_tag":[],"class_list":{"0":"post-3695405","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-blue-sea-systems-pt","7":"product_cat-disjuntores-e-reles","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/3695405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/comments?post=3695405"}],"version-history":[{"count":0,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/3695405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media\/5939243"}],"wp:attachment":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media?parent=3695405"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_brand?post=3695405"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_cat?post=3695405"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_tag?post=3695405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}