{"id":747822,"date":"2025-03-03T21:00:50","date_gmt":"2025-03-03T20:00:50","guid":{"rendered":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/producto\/cubos-de-bronze-para-veio-da-helice-30-mm\/"},"modified":"2026-02-25T00:27:54","modified_gmt":"2026-02-25T00:27:54","slug":"cubos-de-bronze-para-veio-da-helice-30-mm","status":"publish","type":"product","link":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/product\/cubos-de-bronze-para-veio-da-helice-30-mm\/","title":{"rendered":"Cubos de Bronze para Veio da H\u00e9lice 30 mm"},"content":{"rendered":"<p>Cubos de Bronze para Veio da H\u00e9lice 30 mm &#8211; <\/p>\n<p>Os suportes de bronze para eixos de h\u00e9lice s\u00e3o projetados especificamente para veleiros e destinam-se a serem montados com resina na quilha. Esses suportes oferecem v\u00e1rias vantagens para os construtores de navios, incluindo:<\/p>\n<ul>\n<li>Ajustes vers\u00e1teis de altura e \u00e2ngulo<\/li>\n<li>Instala\u00e7\u00e3o r\u00e1pida e f\u00e1cil<\/li>\n<li>Disponibilidade imediata em estoque<\/li>\n<\/ul>\n<p>As dimens\u00f5es desses suportes atendem \u00e0s regulamenta\u00e7\u00f5es estabelecidas pelo Registro Naval Italiano para embarca\u00e7\u00f5es de prazer.<\/p>\n<p>Utilizamos nossa liga OT.MAN, que possui as seguintes propriedades mec\u00e2nicas:<\/p>\n<ul>\n<li>Resist\u00eancia \u00e0 tra\u00e7\u00e3o (T) > 535 N\/mm\u00b2<\/li>\n<li>Limite de elasticidade (Y) > 220 N\/mm\u00b2<\/li>\n<li>Alongamento (E) > 25%<\/li>\n<\/ul>\n<p>Cada suporte vem com rolamentos de borracha hidrolubrificados Radice j\u00e1 instalados.<\/p>\n<p>Esses rolamentos podem ser facilmente substitu\u00eddos soltando as duas porcas de bloqueio. Para instalar os suportes, siga estas etapas:<\/p>\n<ol>\n<li>Crie uma fenda no casco ou na estrutura existente.<\/li>\n<li>Posicione o suporte alinhando-o com a linha do eixo.<\/li>\n<li>Selagem e refor\u00e7o da \u00e1rea de uni\u00e3o entre o suporte e o casco com resina.<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Cubos de Bronze para Veio da H\u00e9lice 30 mm &#8211; Os suportes de bronze para eixos de h\u00e9lice s\u00e3o projetados<\/p>\n","protected":false},"featured_media":5940486,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[2917],"product_cat":[2099,2073],"product_tag":[],"class_list":{"0":"post-747822","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-eliche-radice-pt","7":"product_cat-rolamentos-do-veio-de-propulsao","8":"product_cat-veios-de-helice","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/747822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/comments?post=747822"}],"version-history":[{"count":0,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product\/747822\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media\/5940486"}],"wp:attachment":[{"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/media?parent=747822"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_brand?post=747822"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_cat?post=747822"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/stoic-curie.212-227-153-4.plesk.page\/pt\/wp-json\/wp\/v2\/product_tag?post=747822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}